﻿{"id":281,"date":"2012-10-25T11:55:49","date_gmt":"2012-10-25T16:55:49","guid":{"rendered":"https:\/\/www.uv.mx\/mc-salud\/?p=281"},"modified":"2026-02-23T13:16:06","modified_gmt":"2026-02-23T19:16:06","slug":"requisitos-tmp","status":"publish","type":"post","link":"https:\/\/www.uv.mx\/mc-salud\/2012\/10\/25\/requisitos-tmp\/","title":{"rendered":"Requisitos"},"content":{"rendered":"<p style=\"text-align: justify\"><strong>REQUISITOS DE INGRESO.<\/strong><\/p>\n<ol>\n<li>Carta de aceptaci\u00f3n de un investigador del n\u00facleo acad\u00e9mico del programa, el cual fungir\u00e1 como tutor acad\u00e9mico y director de tesis (<a href=\"https:\/\/www.uv.mx\/mc-salud\/files\/2024\/04\/C_1Carta_aceptacion_MCS.docx\">descargar formato<\/a>).<\/li>\n<li>Certificado de estudios de licenciatura con promedio m\u00ednimo de ocho.<\/li>\n<li>T\u00edtulo profesional de licenciatura, el cual a criterio del Comit\u00e9 de Admisi\u00f3n deber\u00e1 ser af\u00edn al programa de la Maestr\u00eda.<\/li>\n<li>Curriculum vitae (<a href=\"https:\/\/www.uv.mx\/mc-salud\/files\/2025\/03\/C_1FormatoCurriculumvitaeMCS.docx\" rel=\"noopener noreferrer\">descargar formato<\/a>).<\/li>\n<li>Presentar un proyecto de investigaci\u00f3n\u00a0(<a title=\"Guia Anteproyecto\" href=\"https:\/\/www.uv.mx\/dcs\/files\/2015\/04\/GuiaAnteproyectoDCS2014.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">descargar gu\u00eda<\/a>) avalado por su tutor ante el Comit\u00e9 de Admisi\u00f3n, el cual se perfilar\u00e1 como su tema de tesis. La investigaci\u00f3n que se realice, deber\u00e1 ser congruente con las l\u00edneas de generaci\u00f3n y aplicaci\u00f3n del conocimiento de la Maestr\u00eda. Este documento deber\u00e1 contener en la portada la firma del director de tesis.<\/li>\n<li>Carta de exposici\u00f3n de motivos (se exponen los motivos por los que desea ingresar al programa, en formato libre).<\/li>\n<li>Carta compromiso de dedicaci\u00f3n de tiempo completo al posgrado (<a title=\"Carta Compromiso\" href=\"https:\/\/www.uv.mx\/mc-salud\/?attachment_id=356\" target=\"_blank\" rel=\"noopener noreferrer\">descargar formato<\/a>).<\/li>\n<li>Dos cartas de recomendaci\u00f3n de acad\u00e9micos que no pertenezcan al N\u00facleo Acad\u00e9mico B\u00e1sico (NAB) del posgrado (<a href=\"https:\/\/www.uv.mx\/mc-salud\/files\/2026\/02\/C_1_EjemploCartaRecomendacion.docx\" target=\"_blank\" rel=\"noopener noreferrer\">descargar formato<\/a>). Deber\u00e1n ser enviadas por el acad\u00e9mico directamente al correo de la coordinadora <a href=\"mailto:besalas@uv.mx\">besalas@uv.mx<\/a><\/li>\n<li>Acreditar el EXAVER I, o equivalente.<\/li>\n<li>Presentar y aprobar el EXANI III.<\/li>\n<\/ol>\n<p style=\"text-align: justify\"><strong>Requisitos para estudiantes extranjeros:<\/strong><\/p>\n<ol style=\"text-align: justify\">\n<li>Todos los anteriores.<\/li>\n<li>Certificado del dominio del idioma espa\u00f1ol en caso de que \u00e9ste no sea su lengua materna.<\/li>\n<li>Apostilla de t\u00edtulo del \u00faltimo grado.<\/li>\n<\/ol>\n<p style=\"text-align: justify\"><strong>Criterios de evaluaci\u00f3n y ponderaci\u00f3n:<\/strong><\/p>\n<ol>\n<li>EXANI III 15%<\/li>\n<li>Evaluaci\u00f3n Especial (EVE) 85%<\/li>\n<\/ol>\n<p style=\"padding-left: 40px\">EVE consiste en:<\/p>\n<ul>\n<li style=\"list-style-type: none\">\n<ul>\n<li>Entrevista 30%<\/li>\n<li>Proyecto 50%<\/li>\n<li>Curriculum Vitae 10%<\/li>\n<li>Carta de Exposici\u00f3n de Motivos (CEM) 10%<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p style=\"text-align: justify\"><strong>Fechas clave:<\/strong><\/p>\n<ul>\n<li>Sesi\u00f3n informativa: se llevar\u00e1n a cabo v\u00eda videoconferencia. Solicitar fecha al coordinador del programa en el correo etamariz@uv.mx<\/li>\n<li>Inscripciones EXAVER I: verificar fechas en la P\u00e1gina de la UV<\/li>\n<li>Aplicaci\u00f3n de Examen EXANI III: <strong>07 de junio 2025<\/strong>.<\/li>\n<li>Entrega de documentos v\u00eda electr\u00f3nica a trav\u00e9s del <a href=\"https:\/\/forms.gle\/pTY6tkNm4FMx9U6H8\" target=\"_blank\" rel=\"noopener\">formulario en l\u00ednea<\/a>: <strong>del 02<\/strong><b> al 06 de junio de 2025<\/b>.<\/li>\n<li>Entrevista de selecci\u00f3n y presentaci\u00f3n de proyectos: <b>del 11 al 20 de junio de 2025<\/b>.<\/li>\n<li>Publicaci\u00f3n de resultados: <strong>11<\/strong><b> de julio de 2025<\/b>.<\/li>\n<li>Inscripciones: del <b>04 al 08 de agosto de 2025<\/b>.<\/li>\n<\/ul>\n<p><strong>REQUISITOS DE PERMANENCIA.<br \/>\n<\/strong><\/p>\n<ol style=\"text-align: justify\">\n<li>Aprobar los cursos o experiencias educativas con un m\u00ednimo de 70 en una escala de calificaci\u00f3n del 1 al 100.<\/li>\n<li>Cumplir con las sesiones de asesor\u00eda con su tutor.<\/li>\n<li>Al finalizar cada periodo, entregar informe de avance de tesis avalado por el\u00a0tutor\/director de tesis.<\/li>\n<li>Entregar durante el cuarto semestre certificado de acreditaci\u00f3n del EXAVER II.<\/li>\n<\/ol>\n<p style=\"text-align: justify\"><strong>REQUISITOS DE EGRESO.<\/strong><\/p>\n<ol style=\"text-align: justify\">\n<li>Para obtener el grado de Maestr\u00eda el egresado deber\u00e1 cumplir con los requisitos establecidos en el Reglamento de Estudios de Posgrado vigente.<\/li>\n<li>Haber cumplido en su totalidad el plan de estudio correspondiente de la maestr\u00eda.<\/li>\n<li>Las dem\u00e1s disposiciones que establece el Reglamento Interno de la maestr\u00eda.<\/li>\n<\/ol>\n<p style=\"text-align: justify\"><strong>REQUISITOS DE TITULACI\u00d3N.<\/strong><\/p>\n<ol style=\"text-align: justify\">\n<li>El programa de la Maestr\u00eda en Ciencias de la Salud contempla como \u00fanica opci\u00f3n para obtener el grado, la presentaci\u00f3n y defensa del trabajo de tesis, dicho mecanismo est\u00e1 fundamentado en el Cap\u00edtulo XII Art\u00edculo 70 (A), del Reglamento General de Estudios de Posgrado (RGEP) de la Universidad Veracruzana, el procedimiento completo se encuentra asentado en el Reglamento Interno (C) de la maestr\u00eda en los art\u00edculos 66 a 74.<\/li>\n<li>Para tener acceso a este procedimiento son requisitos indispensables los siguientes:<\/li>\n<\/ol>\n<ul style=\"text-align: justify\">\n<li style=\"list-style-type: none\">\n<ul>\n<li>Aprobar la totalidad de los cursos o experiencias educativas cursados en la maestr\u00eda con calificaci\u00f3n m\u00ednima de 70.<\/li>\n<li>Cubrir el 100% de los cr\u00e9ditos del plan de estudios.<\/li>\n<li>Obtener promedio general m\u00ednimo de 70.<\/li>\n<li>Adem\u00e1s de los se\u00f1alados en el RGEP.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p style=\"text-align: justify\">A) De acuerdo al Reglamento General de Estudios de Posgrado 2023:<\/p>\n<p style=\"text-align: justify\">CAP\u00cdTULO X<\/p>\n<ul>\n<li class=\"elementToProof\">\n<div>De los diplomas o grados acad\u00e9micos<\/div>\n<\/li>\n<li class=\"elementToProof\">\n<div>Secci\u00f3n segunda. De los grados acad\u00e9micos.<\/div>\n<\/li>\n<li class=\"elementToProof\">\n<div>Art\u00edculo 66. Para obtener el grado de maestr\u00eda o doctorado en la Universidad Veracruzana, es indispensable presentar un trabajo recepcional cuya estructura ser\u00e1 establecida en el plan de estudios del programa educativo correspondiente, el cual deber\u00e1 ser defendido ante un jurado.<\/div>\n<div>No son v\u00e1lidos los trabajos recepcionales colectivos.<\/div>\n<\/li>\n<\/ul>\n<p style=\"text-align: justify\">B) De acuerdo al Plan de Estudios de la maestr\u00eda<\/p>\n<p style=\"text-align: justify\">1. Requisitos de egreso y presentaci\u00f3n de examen grado.<\/p>\n<ul style=\"text-align: justify\">\n<li>Para obtener el grado de Maestr\u00eda el egresado deber\u00e1 cumplir con los requisitos establecidos en el Reglamento de Estudios de Posgrado vigente.<\/li>\n<li>Haber cumplido en su totalidad el plan de estudio correspondiente de la maestr\u00eda;<\/li>\n<li>Las dem\u00e1s disposiciones que establece el Reglamento Interno de la maestr\u00eda;<\/li>\n<\/ul>\n<p style=\"text-align: justify\">2. Requisitos de titulaci\u00f3n.<br \/>\nPara obtener el grado de maestr\u00eda, el alumno deber\u00e1:<\/p>\n<ul style=\"text-align: justify\">\n<li>Haber cumplido en su totalidad el plan de estudio correspondiente de la maestr\u00eda.<\/li>\n<li>Aprobar el examen de grado que consistir\u00e1 en la defensa p\u00fablica de su trabajo de\u00a0tesis individual.<\/li>\n<\/ul>\n<p style=\"text-align: justify\"><strong>CAMPO DE TRABAJO.<\/strong><\/p>\n<ul style=\"text-align: justify\">\n<li>Instituciones de educaci\u00f3n superior.<\/li>\n<li>Institutos y Centros de Investigaci\u00f3n.<\/li>\n<li>Instituciones de Salud (hospitales).<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>REQUISITOS DE INGRESO. Carta de aceptaci\u00f3n de un investigador del n\u00facleo acad\u00e9mico del programa, el cual fungir\u00e1 como tutor acad\u00e9mico y director de tesis (descargar formato). Certificado de estudios de licenciatura con promedio m\u00ednimo de ocho. T\u00edtulo profesional de licenciatura, el cual a criterio del Comit\u00e9 de Admisi\u00f3n deber\u00e1 ser af\u00edn al programa de la [&hellip;]<\/p>\n","protected":false},"author":1306,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ventana_nueva":"","tipo_url":"","url":"","extracto":"","imagen_halign":"","imagen_valign":"","bg_size":"","text_hide":"","media_url":"","tipo_media":"","video_url":"","video_pos":"","video_youtube":"","footnotes":""},"categories":[5],"tags":[],"class_list":["post-281","post","type-post","status-publish","format-standard","hentry","category-aspirantes"],"_links":{"self":[{"href":"https:\/\/www.uv.mx\/mc-salud\/wp-json\/wp\/v2\/posts\/281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uv.mx\/mc-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uv.mx\/mc-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uv.mx\/mc-salud\/wp-json\/wp\/v2\/users\/1306"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uv.mx\/mc-salud\/wp-json\/wp\/v2\/comments?post=281"}],"version-history":[{"count":3,"href":"https:\/\/www.uv.mx\/mc-salud\/wp-json\/wp\/v2\/posts\/281\/revisions"}],"predecessor-version":[{"id":1232,"href":"https:\/\/www.uv.mx\/mc-salud\/wp-json\/wp\/v2\/posts\/281\/revisions\/1232"}],"wp:attachment":[{"href":"https:\/\/www.uv.mx\/mc-salud\/wp-json\/wp\/v2\/media?parent=281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uv.mx\/mc-salud\/wp-json\/wp\/v2\/categories?post=281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uv.mx\/mc-salud\/wp-json\/wp\/v2\/tags?post=281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}