﻿{"id":2649,"date":"2021-07-13T18:52:25","date_gmt":"2021-07-13T23:52:25","guid":{"rendered":"https:\/\/www.uv.mx\/dic\/?p=2649"},"modified":"2024-04-25T12:47:23","modified_gmt":"2024-04-25T17:47:23","slug":"uso-de-espacios-comunes","status":"publish","type":"post","link":"https:\/\/www.uv.mx\/dic\/general\/uso-de-espacios-comunes\/","title":{"rendered":"Uso de espacios comunes"},"content":{"rendered":"<p><strong>Para reservar un espacio o equipo pulsa sobre el \u00e1rea de tu inter\u00e9s, consulta las fechas y horarios disponibles y env\u00eda tu solicitud a los correos que se indican.<\/strong><\/p>\n<p>NOTA IMPORTANTE: No se reservar\u00e1 el equipo en d\u00edas y horarios en los que est\u00e9n programadas actividades acad\u00e9micas del IICE a las que todos los alumnos del doctorado est\u00e9n convocados. Por ejemplo: los martes de 9:30 a 12:30 horas, cuando se celebran los seminarios institucionales.<\/p>\n<p>&nbsp;<\/p>\n<table style=\"border-collapse: collapse;width: 100%\" border=\"1\">\n<tbody>\n<tr>\n<td style=\"width: 50%\"><a href=\"https:\/\/forms.office.com\/Pages\/ResponsePage.aspx?id=UXaQPMbYpkyopGokJDDmU-HUMYCvGblAtX-sjT0Pap1UODhJVE8zSVdGVDNJUlFVUlBUUDY5WUM2VS4u\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-3994\" src=\"https:\/\/www.uv.mx\/dic\/files\/2021\/07\/Registro-usuario-1-300x300.jpg\" alt=\"\" width=\"350\" height=\"350\" srcset=\"https:\/\/www.uv.mx\/dic\/files\/2021\/07\/Registro-usuario-1-300x300.jpg 300w, https:\/\/www.uv.mx\/dic\/files\/2021\/07\/Registro-usuario-1-1024x1024.jpg 1024w, https:\/\/www.uv.mx\/dic\/files\/2021\/07\/Registro-usuario-1-150x150.jpg 150w, https:\/\/www.uv.mx\/dic\/files\/2021\/07\/Registro-usuario-1-768x768.jpg 768w, https:\/\/www.uv.mx\/dic\/files\/2021\/07\/Registro-usuario-1.jpg 1080w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/a><\/td>\n<td style=\"width: 50%\">\n<p><strong>AVISO IMPORTANTE\u00a0<\/strong><\/p>\n<p>Todas las personas que realizan pr\u00e1cticas en el IICE y que <b style=\"font-family: inherit;font-size: inherit\">no<\/b><span style=\"font-family: inherit;font-size: inherit\">\u00a0<\/span><b style=\"font-family: inherit;font-size: inherit\">est\u00e1n inscritas<\/b><span style=\"font-family: inherit;font-size: inherit\"> en el Doctorado en Investigaciones Cerebrales (tesistas de licenciatura o maestr\u00eda, prestadores de servicio social, realizadores de pr\u00e1cticas profesionales, egresados del DIC que continuar\u00e1n trabajando, postdoctores, etc.) deben ser registradas en este formulario por el investigador que funge como director de tesis o jefe inmediato.<\/span><\/p>\n<p>(Pulse sobre el icono que aparece a la izquierda para acceder al formulario).<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<table style=\"border-collapse: collapse;width: 100%\" border=\"1\">\n<tbody>\n<tr>\n<td style=\"width: 50%\"><a href=\"https:\/\/www.uv.mx\/dic\/general\/microscopia\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2562\" src=\"https:\/\/www.uv.mx\/dic\/files\/2021\/05\/UnidadMicroscopia-1024x341.png\" alt=\"Pulsa para reservar\" width=\"500\" height=\"167\" srcset=\"https:\/\/www.uv.mx\/dic\/files\/2021\/05\/UnidadMicroscopia-1024x341.png 1024w, https:\/\/www.uv.mx\/dic\/files\/2021\/05\/UnidadMicroscopia-300x100.png 300w, https:\/\/www.uv.mx\/dic\/files\/2021\/05\/UnidadMicroscopia-768x256.png 768w, https:\/\/www.uv.mx\/dic\/files\/2021\/05\/UnidadMicroscopia.png 1500w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/td>\n<td style=\"width: 50%\"><a href=\"https:\/\/www.uv.mx\/dic\/general\/criostato\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2647\" src=\"https:\/\/www.uv.mx\/dic\/files\/2021\/07\/Criostato-1024x341.png\" alt=\"Pulsa para reservar\" width=\"500\" height=\"167\" srcset=\"https:\/\/www.uv.mx\/dic\/files\/2021\/07\/Criostato-1024x341.png 1024w, https:\/\/www.uv.mx\/dic\/files\/2021\/07\/Criostato-300x100.png 300w, https:\/\/www.uv.mx\/dic\/files\/2021\/07\/Criostato-768x256.png 768w, https:\/\/www.uv.mx\/dic\/files\/2021\/07\/Criostato.png 1500w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<table style=\"border-collapse: collapse;width: 100%\" border=\"1\">\n<tbody>\n<tr>\n<td style=\"width: 50%\"><a href=\"https:\/\/www.uv.mx\/dic\/general\/microtomo\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3255\" src=\"https:\/\/www.uv.mx\/dic\/files\/2021\/07\/Microtomo-iice-1024x341.png\" alt=\"\" width=\"500\" height=\"167\" srcset=\"https:\/\/www.uv.mx\/dic\/files\/2021\/07\/Microtomo-iice-1024x341.png 1024w, https:\/\/www.uv.mx\/dic\/files\/2021\/07\/Microtomo-iice-300x100.png 300w, https:\/\/www.uv.mx\/dic\/files\/2021\/07\/Microtomo-iice-768x256.png 768w, https:\/\/www.uv.mx\/dic\/files\/2021\/07\/Microtomo-iice.png 1500w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/td>\n<td style=\"width: 50%\"><a href=\"https:\/\/www.uv.mx\/dic\/general\/aula-hibrida\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3287\" src=\"https:\/\/www.uv.mx\/dic\/files\/2021\/07\/Verde-Rojo-Campechana-Navidad-Follaje-Encabezado-de-Twitter-1024x341.jpg\" alt=\"\" width=\"500\" height=\"167\" srcset=\"https:\/\/www.uv.mx\/dic\/files\/2021\/07\/Verde-Rojo-Campechana-Navidad-Follaje-Encabezado-de-Twitter-1024x341.jpg 1024w, https:\/\/www.uv.mx\/dic\/files\/2021\/07\/Verde-Rojo-Campechana-Navidad-Follaje-Encabezado-de-Twitter-300x100.jpg 300w, https:\/\/www.uv.mx\/dic\/files\/2021\/07\/Verde-Rojo-Campechana-Navidad-Follaje-Encabezado-de-Twitter-768x256.jpg 768w, https:\/\/www.uv.mx\/dic\/files\/2021\/07\/Verde-Rojo-Campechana-Navidad-Follaje-Encabezado-de-Twitter.jpg 1500w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.uv.mx\/dic\/general\/microtomo\/\" target=\"_blank\" rel=\"noopener\">\u00a0<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para reservar un espacio o equipo pulsa sobre el \u00e1rea de tu inter\u00e9s, consulta las fechas y horarios disponibles y env\u00eda tu solicitud a los correos que se indican. NOTA IMPORTANTE: No se reservar\u00e1 el equipo en d\u00edas y horarios en los que est\u00e9n programadas actividades acad\u00e9micas del IICE a las que todos los alumnos [&hellip;]<\/p>\n","protected":false},"author":1696,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ventana_nueva":"","tipo_url":"","url":"","extracto":"","imagen_halign":"","imagen_valign":"","bg_size":"","text_hide":"","media_url":"","tipo_media":"","video_url":"","video_pos":"","video_youtube":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-2649","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.uv.mx\/dic\/wp-json\/wp\/v2\/posts\/2649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uv.mx\/dic\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uv.mx\/dic\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uv.mx\/dic\/wp-json\/wp\/v2\/users\/1696"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uv.mx\/dic\/wp-json\/wp\/v2\/comments?post=2649"}],"version-history":[{"count":2,"href":"https:\/\/www.uv.mx\/dic\/wp-json\/wp\/v2\/posts\/2649\/revisions"}],"predecessor-version":[{"id":3995,"href":"https:\/\/www.uv.mx\/dic\/wp-json\/wp\/v2\/posts\/2649\/revisions\/3995"}],"wp:attachment":[{"href":"https:\/\/www.uv.mx\/dic\/wp-json\/wp\/v2\/media?parent=2649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uv.mx\/dic\/wp-json\/wp\/v2\/categories?post=2649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uv.mx\/dic\/wp-json\/wp\/v2\/tags?post=2649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}