﻿{"id":9649,"date":"2015-10-05T11:14:26","date_gmt":"2015-10-05T16:14:26","guid":{"rendered":"https:\/\/www.uv.mx\/daduv\/?p=9649"},"modified":"2015-10-05T11:14:26","modified_gmt":"2015-10-05T16:14:26","slug":"xalapa-alzo-el-titulo-en-el-voleibol-del-festival-deportivo","status":"publish","type":"post","link":"https:\/\/www.uv.mx\/daduv\/noticias-recientes\/xalapa-alzo-el-titulo-en-el-voleibol-del-festival-deportivo\/","title":{"rendered":"Xalapa alz\u00f3 el t\u00edtulo en el Voleibol, del Festival Deportivo"},"content":{"rendered":"<p>Los equipos representativos de la Regi\u00f3n Xalapa, de manera contundente se alzaron con los t\u00edtulos varonil y femenil\u00a0 del certamen\u00a0 de voleibol, del Festival Deportivo Universitario, el m\u00e1ximo evento anual al interior de la Universidad Veracruzana.<\/p>\n<p>La cuarta victoria del sexteto femenil, de UV-Xalapa, fue ante la representaci\u00f3n de Orizaba-C\u00f3rdoba, a la que derrotaron en dos sets de 25-12 y 25-19: antes ganaron a Coatza-Mina por 25-10 y 25-11; en la segunda llamada superaron al colectivo de Veracruz-Boca del R\u00edo, por ajustados, parciales de 25-18 y 26-24 e iniciaron su participaci\u00f3n derrotando por 25-8 y 25-9 a Poza Rica-Tuxpan .<\/p>\n<p>Por lo que respecta al representativo varonil de Halcones-UV, al mando de Jos\u00e9 Israel Solar Flores, tambi\u00e9n llegaron a la corona imbatibles, al iniciar el torneo, ganaron 25-23 y 25-12 a Poza Rica-Tuxpan; despu\u00e9s en dram\u00e1tico juego, que es un cl\u00e1sico, superaron a Veracruz-Boca del R\u00edo, en tres sets de 25-21, 21-25 y 15-7. La tercera victoria sobre Coatza-Mina por 26-24 y 25-22 y cerraron ganando en dos sets de 25-19 y 25-15 sobre Orizaba-C\u00f3rdoba.<\/p>\n<p>En la \u00faltima jornada celebrada por la ma\u00f1ana de \u00e9ste viernes, en el Gimnasio Universitario \u201cMiguel Angel R\u00edos Torres\u201d, Veracruz se impuso en dos sets de 25-11 y 25-13 a Coatza-Mina; en misma rama, Poza Rica-Tuxpan,\u00a0 pas\u00f3 sobre Orizaba-C\u00f3rdoba por 25-19 y 25-22; en rama femenil, Veracruz derrot\u00f3 25-4 y 25-13 a Coatza-Mina y Orizaba-C\u00f3rdoba gan\u00f3 25-14 y 25-17 a Poza Rica Tuxpan.<\/p>\n<p>El festival deportivo universitario, que en su primera parte se realiz\u00f3 en la regi\u00f3n Orizaba-C\u00f3rdoba, llegar\u00e1 a su t\u00e9rmino \u00e9ste s\u00e1bado, al celebrarse la \u00faltima jornada del Torneo de Voleibol Playero, con actividad desde las nueve de la ma\u00f1ana, en la cancha enclavada en la Unidad Deportiva Universitaria. En rama varonil, intervienen siete equipos, dos de Veracruz y Xalapa y con uno, Coatza-Mina, Poza Rica-Tuxpan y Orizaba-C\u00f3rdoba.<\/p>\n<p>El torneo, se puso en marcha la tarde de \u00e9ste viernes, con actividad desde las tres de la tarde, en tanto que la jornada sabatina, \u00a0abre a las nueve de la ma\u00f1ana y se tiene previsto, culmine justo al mediod\u00eda y un hasta pronto, ya que los triunfadores, tanto en los deportes individuales como de conjunto defender\u00e1n los colores de la Universidad Veracruzana, en los Juegos Deportivos Estatales de Educaci\u00f3n Superior, antesala de los Regiones, rumbo a la Universiada Nacional Guadalajara-2016.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los equipos representativos de la Regi\u00f3n Xalapa, de manera contundente se alzaron con los t\u00edtulos varonil y femenil\u00a0 del certamen\u00a0 de voleibol, del Festival Deportivo Universitario, el m\u00e1ximo evento anual al interior de la Universidad Veracruzana. La cuarta victoria del sexteto femenil, de UV-Xalapa, fue ante la representaci\u00f3n de Orizaba-C\u00f3rdoba, a la que derrotaron en [&hellip;]<\/p>\n","protected":false},"author":1549,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ventana_nueva":"","tipo_url":"","url":"","extracto":"","imagen_halign":"","imagen_valign":"","bg_size":"","text_hide":"","media_url":"","tipo_media":"","video_url":"","video_pos":"","video_youtube":"","footnotes":""},"categories":[16],"tags":[],"class_list":["post-9649","post","type-post","status-publish","format-standard","hentry","category-noticias-recientes"],"_links":{"self":[{"href":"https:\/\/www.uv.mx\/daduv\/wp-json\/wp\/v2\/posts\/9649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uv.mx\/daduv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uv.mx\/daduv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uv.mx\/daduv\/wp-json\/wp\/v2\/users\/1549"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uv.mx\/daduv\/wp-json\/wp\/v2\/comments?post=9649"}],"version-history":[{"count":0,"href":"https:\/\/www.uv.mx\/daduv\/wp-json\/wp\/v2\/posts\/9649\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.uv.mx\/daduv\/wp-json\/wp\/v2\/media?parent=9649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uv.mx\/daduv\/wp-json\/wp\/v2\/categories?post=9649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uv.mx\/daduv\/wp-json\/wp\/v2\/tags?post=9649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}