﻿{"id":8174,"date":"2015-02-18T14:19:12","date_gmt":"2015-02-18T20:19:12","guid":{"rendered":"https:\/\/www.uv.mx\/daduv\/?p=8174"},"modified":"2018-03-06T08:50:55","modified_gmt":"2018-03-06T14:50:55","slug":"boletin-1283","status":"publish","type":"post","link":"https:\/\/www.uv.mx\/daduv\/boletines-de-prensa\/boletin-1283\/","title":{"rendered":"Bolet\u00edn 1283"},"content":{"rendered":"<p>UNIVERSIDAD VERACRUZANA(DADUV) bol.#1283<\/p>\n<p><strong>HALCONES-UV, 85-74 A UMAD, EN BASQUET-ABE<\/strong><\/p>\n<p><em>(*).-HOY ANTE AZTECAS DE LA UDLAP.<\/em><\/p>\n<p>Xalapa, Equez., Ver., 13 de febrero del 2015.-Buen retorno a casa, despu\u00e9s de abrir de visitantes la segunda parte de la segunda campa\u00f1a de la Asociaci\u00f3n de Basquetbol Estudiantil, el ABE, los \u00a0Halcones de la Universidad Veracruzana, tuvieron brillante reaparici\u00f3n en casa, al superar categ\u00f3ricamente a la Universidad Madero de Puebla, la UMAD, ante entusiasta p\u00fablico reunido en el vetusto Gimnasio universitario \u00abMiguel Angel R\u00edos Torres\u00bb.<\/p>\n<p>Los plum\u00edferos comandados por\u00a0\u00a0 Leo Hern\u00e1ndez, implement\u00f3 una nueva din\u00e1mica en la plantilla, lo que entendieron porque\u00a0 marcaba el primer tiempo, los dos primeros cuartos y ten\u00edan abajo a la UMAD por 54-37, para as\u00ed irse al descanso.<\/p>\n<p>Provechoso el receso para ajustar l\u00edneas, pero a\u00fan as\u00ed ten\u00edan ventaja de veinte puntos, pero la UMAD no baj\u00f3 los brazos, al grado que se les acercaron peligrosamente en el marcador, pero al final la victoria de la mano de Roberto Aguilar, quien anot\u00f3 26 puntos, en tanto que por los \u00a0visitantes,. Manuel Y\u00e1\u00f1ez, colabor\u00f3 con 37.<\/p>\n<p>Con la mentalidad por la nubes, los Halcones de la Universidad Veracruzana, \u00e9ste s\u00e1bado 14 de febrero, a partir de las 13:00 horas, (una de la tarde), en el mismo Gimnasio Universitario \u00abMiguel Angel R\u00edos Torres en duelo de la jornada 35, semana once de actividad del ABE, enfrentar\u00e1 nada menos que a uno de los equipos \u00a0l\u00edderes del torneo, a los Aztecas\u00a0de la Universidad de Las Am\u00e9ricas de Cholula, Puebla, la UDLAP.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>UNIVERSIDAD VERACRUZANA(DADUV) bol.#1283 HALCONES-UV, 85-74 A UMAD, EN BASQUET-ABE (*).-HOY ANTE AZTECAS DE LA UDLAP. Xalapa, Equez., Ver., 13 de febrero del 2015.-Buen retorno a casa, despu\u00e9s de abrir de visitantes la segunda parte de la segunda campa\u00f1a de la Asociaci\u00f3n de Basquetbol Estudiantil, el ABE, los \u00a0Halcones de la Universidad Veracruzana, tuvieron brillante reaparici\u00f3n [&hellip;]<\/p>\n","protected":false},"author":1549,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ventana_nueva":"","tipo_url":"","url":"","extracto":"","imagen_halign":"","imagen_valign":"","bg_size":"","text_hide":"","media_url":"","tipo_media":"","video_url":"","video_pos":"","video_youtube":"","footnotes":""},"categories":[27],"tags":[],"class_list":["post-8174","post","type-post","status-publish","format-standard","hentry","category-boletines-de-prensa"],"_links":{"self":[{"href":"https:\/\/www.uv.mx\/daduv\/wp-json\/wp\/v2\/posts\/8174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uv.mx\/daduv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uv.mx\/daduv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uv.mx\/daduv\/wp-json\/wp\/v2\/users\/1549"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uv.mx\/daduv\/wp-json\/wp\/v2\/comments?post=8174"}],"version-history":[{"count":0,"href":"https:\/\/www.uv.mx\/daduv\/wp-json\/wp\/v2\/posts\/8174\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.uv.mx\/daduv\/wp-json\/wp\/v2\/media?parent=8174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uv.mx\/daduv\/wp-json\/wp\/v2\/categories?post=8174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uv.mx\/daduv\/wp-json\/wp\/v2\/tags?post=8174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}