﻿{"id":2840,"date":"2014-06-24T13:03:24","date_gmt":"2014-06-24T18:03:24","guid":{"rendered":"https:\/\/www.uv.mx\/cienciauv\/?p=2840"},"modified":"2014-06-24T13:29:53","modified_gmt":"2014-06-24T18:29:53","slug":"quimicacolor","status":"publish","type":"post","link":"https:\/\/www.uv.mx\/cienciauv\/blog\/quimicacolor\/","title":{"rendered":"La Qu\u00edmica del Color"},"content":{"rendered":"<p><b>\u00a0<\/b><\/p>\n<p style=\"text-align: right\"><a href=\"https:\/\/www.uv.mx\/cienciauv\/files\/2014\/06\/Quimica-del-color-03.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-2844\" alt=\"-Qu\u00edmica del color-03\" src=\"https:\/\/www.uv.mx\/cienciauv\/files\/2014\/06\/Quimica-del-color-03-1024x197.jpg\" width=\"1024\" height=\"197\" srcset=\"https:\/\/www.uv.mx\/cienciauv\/files\/2014\/06\/Quimica-del-color-03-1024x197.jpg 1024w, https:\/\/www.uv.mx\/cienciauv\/files\/2014\/06\/Quimica-del-color-03-300x57.jpg 300w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p style=\"text-align: right\"><em><strong>\u00a0Ra\u00fal Colorado Peralta y Jos\u00e9 Mar\u00eda Rivera*<\/strong><\/em><\/p>\n<p><strong>Nuestro mundo se ve muy bien a colores, a todos nos gusta contemplar el campo verde, el cielo azul o las flores. Pero no s\u00f3lo la naturaleza es colorida, nos gustan tanto los colores que los capturamos en nuestros objetos, pintamos nuestras casas, te\u00f1imos la ropa, imprimimos fotograf\u00edas, tenemos una televisi\u00f3n a colores, comemos alimentos de buen color. La qu\u00edmica y la f\u00edsica son las ciencias que nos dan las herramientas para hacer cualquier color y ponerlo en el lugar que m\u00e1s nos agrade.<\/strong><\/p>\n<p><strong>\u00bfQu\u00e9 es la luz?<\/strong><\/p>\n<p><b>\u00a0<\/b>La luz visible es un fen\u00f3meno complejo, se trata de una forma de radiaci\u00f3n que puede percibir el ojo humano, est\u00e1 compuesta de part\u00edculas que tienen propiedades de onda (como las olas en el mar) y de part\u00edcula (como una canica) y que llevan una energ\u00eda definida. La velocidad de la luz es una constante (299 millones 792 mil 458 metros por segundo), suficiente para viajar por carretera de Tijuana a Chetumal m\u00e1s de 73 veces o para darle casi 7.5 vueltas a la tierra&#8230; \u00a1en un segundo!<\/p>\n<p>El color, por su parte, es la interpretaci\u00f3n que nuestro cerebro le da a los part\u00edculas de luz de diferente longitud de onda. Para que el color exista se necesitan dos cosas: luz que provenga de un objeto y una persona que pueda ver esa luz. Si no est\u00e1n presentes ambas el color no existe.<\/p>\n<p><strong>Bastones y conos&#8230;\u00a1para verte mejor!<\/strong><\/p>\n<p><span style=\"line-height: 1.5em\">Cuando la luz llega a nuestro ojo es enfocada por el cristalino y se forma una imagen invertida en la retina. La luz que llega a la retina provoca una se\u00f1al el\u00e9ctrica que es enviada al cerebro. No vemos las cosas de cabeza\u00a0<\/span><span style=\"line-height: 1.5em\">p<\/span><span style=\"line-height: 1.5em\">orque el cerebro se encarga de procesar la se\u00f1al que le llega por el nervio \u00f3ptico, en el procesamiento endereza la imagen y le asigna los colores. La miop\u00eda, la hipermetrop\u00eda y el astigmatismo son causadas porque el cristalino no es capaz de enfocar bien la imagen sobre la retina.<\/span><\/p>\n<p style=\"text-align: justify\">En la retina hay una capa de c\u00e9lulas llamadas bastones y conos, especializadas en recibir luz y producir la se\u00f1al el\u00e9ctrica que se mandar\u00e1 al cerebro. Estas c\u00e9lulas receptoras reciben su nombre por la forma que tienen. Tenemos un s\u00f3lo tipo de bast\u00f3n y tres tipos de conos sensibles a luz roja, luz azul o luz verde. El cerebro interpreta los tres colores b\u00e1sicos aditivos y los combina para producir el resto de los colores, tal\u00a0<span style=\"line-height: 1.5em\">como lo hacen los televisores\u00a0<\/span><span style=\"line-height: 1.5em\"><span style=\"text-align: justify;line-height: 1.5em\">\u00a0<\/span>y monitores.\u00a0<\/span><\/p>\n<p>\u00a0<span style=\"text-align: justify;line-height: 1.5em\">En la retina tenemos aproximadamente 110 millones de bastones, son c\u00e9lulas muy sensibles que est\u00e1n activas cuando hay poca luz, casi en la total oscuridad. Al existir s\u00f3lo un tipo de bastones la se\u00f1al que le llega al cerebro es monocrom\u00e1tica y vemos en blanco y negro. Tenemos en nuestros ojos unos 7 millones de los tres tipos de conos para ver con mucha luz y son \u00e9stos los responsables de nuestra visi\u00f3n a colores.Aproximadamente el 8 por ciento de los hombres y el 0.5 por ciento de las <a href=\"https:\/\/www.uv.mx\/cienciauv\/files\/2014\/06\/Quimica-del-color-04.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2845 alignright\" alt=\"-Qu\u00edmica del color-04\" src=\"https:\/\/www.uv.mx\/cienciauv\/files\/2014\/06\/Quimica-del-color-04-907x1024.jpg\" width=\"635\" height=\"717\" srcset=\"https:\/\/www.uv.mx\/cienciauv\/files\/2014\/06\/Quimica-del-color-04-907x1024.jpg 907w, https:\/\/www.uv.mx\/cienciauv\/files\/2014\/06\/Quimica-del-color-04-265x300.jpg 265w\" sizes=\"auto, (max-width: 635px) 100vw, 635px\" \/><\/a>mujeres tienen una deficiencia en la visi\u00f3n a colores, siendo la m\u00e1s com\u00fan la deficiencia para percibir el color verde. Pocas personas, por lo general mujeres, tienen en su retina cuatro tipos diferentes de conos, por lo que su percepci\u00f3n de los colores es m\u00e1s rica que la de la mayor\u00eda de la poblaci\u00f3n, mientras que aproximadamente el 2 por ciento de los hombres s\u00f3lo tienen dos tipos de conos y su percepci\u00f3n de los colores es pobre. Las deficiencias en la visi\u00f3n a colores se conocen com\u00fanmente como daltonismo.<\/span><\/p>\n<p style=\"text-align: justify\">Por lo que respecta a los animales, definitivamente no ven los colores como nosotros: La mayor\u00eda de los mam\u00edferos s\u00f3lo tienen dos pigmentos diferentes, lo que implica que ven menos colores que la mayor\u00eda de las personas, los insectos tienen tres pigmentos pero no ven igual que nosotros, las abejas no pueden ver lo que para nosotros es rojo pero pueden ver el ultravioleta que para nosotros es invisible, la mayor\u00eda de las aves tienen cuatro pigmentos diferentes, aunque algunas especies tienen cinco y son capaces de ver todo el visible m\u00e1s la regi\u00f3n ultravioleta, los peces tienen tres o cuatro pigmentos diferentes y seguramente tambi\u00e9n pueden ver una gama de colores m\u00e1s variada. Sin embargo, no podemos saber c\u00f3mo ven los animales porque necesitamos no s\u00f3lo ver a trav\u00e9s de sus ojos, sino tambi\u00e9n tener su cerebro para ver como ellos, es probable que nunca lo sepamos.<\/p>\n<p><strong>Mol\u00e9culas que juegan con la luz<\/strong><\/p>\n<p><span style=\"line-height: 1.5em\">Hay varias formas de producir colores: puede ser por descomposici\u00f3n de la luz blanca, por absorci\u00f3n de luz o por emisi\u00f3n de luz. En el primer caso no es muy importante con qu\u00e9 sustancia est\u00e1 interactuando la luz pero en los dos \u00faltimos s\u00ed importa mucho la estructura at\u00f3mica o molecular de la sustancia.<\/span><\/p>\n<p>El cielo es azul, no porque refleje el color del mar, sino por dispersi\u00f3n de la parte azul de la luz. Esto es provocado por un fen\u00f3meno llamado dispersi\u00f3n de Rayleigh que se manifiesta cuando al llegar la luz del sol a la tierra choca con las mol\u00e9culas de aire, que son principalmente ox\u00edgeno (O2) y nitr\u00f3ge<span style=\"line-height: 1.5em\">no (N2), estas mol\u00e9culas dispersan la luz azul con m\u00e1s fuerza y en lugar de seguir su camino se desv\u00eda y llega a nuestros ojos.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2842 alignleft\" alt=\"-Qu\u00edmica del color-01\" src=\"https:\/\/www.uv.mx\/cienciauv\/files\/2014\/06\/Quimica-del-color-01.jpg\" width=\"242\" height=\"314\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>La difracci\u00f3n es tal vez la forma m\u00e1s conocida de descomposici\u00f3n de la luz.<span style=\"line-height: 1.5em\">\u00a0Este fen\u00f3meno consiste en que la luz se desv\u00eda en cierto \u00e1ngulo al atravesar una sustancia, los colores de la luz blanca se separan porque cada uno se desv\u00eda en un \u00e1ngulo diferente. Esto se observa cuando la luz del sol atraviesa las gotas de lluvia formando un arco iris, pero debido a que se requiere que la luz sea reflejada por el interior de la gota s\u00f3lo podemos ver un arco iris si tenemos el sol a nuestra espalda.<\/span>l vez la forma m\u00e1s conocida de descomposici\u00f3n de la luz.<\/p>\n<p>Muchos creen que el mar es azul por el reflejo del cielo pero no es as\u00ed. El agua se ve azul en grandes cantidades porque de todos los colores que componen la luz blanca el que menos absorbe es el azul, esta absorci\u00f3n es causada por las vibraciones moleculares.<\/p>\n<p>Los fuegos pirot\u00e9cnicos son un espect\u00e1culo multicolor muy usado en ocasiones especiales, para poder hacer esto se utilizan compuestos met\u00e1licos que se a\u00f1aden a la p\u00f3lvora y que al arder brillar\u00e1n de un color en particular.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong style=\"line-height: 1.5em\">\u00bfColores a la medida?<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2843 alignright\" alt=\"-Qu\u00edmica del color-02\" src=\"https:\/\/www.uv.mx\/cienciauv\/files\/2014\/06\/Quimica-del-color-02-1024x646.jpg\" width=\"368\" height=\"233\" srcset=\"https:\/\/www.uv.mx\/cienciauv\/files\/2014\/06\/Quimica-del-color-02-1024x646.jpg 1024w, https:\/\/www.uv.mx\/cienciauv\/files\/2014\/06\/Quimica-del-color-02-300x189.jpg 300w, https:\/\/www.uv.mx\/cienciauv\/files\/2014\/06\/Quimica-del-color-02.jpg 1398w\" sizes=\"auto, (max-width: 368px) 100vw, 368px\" \/><\/p>\n<p style=\"text-align: justify\"><span style=\"text-align: justify;line-height: 1.5em\">Los qu\u00edmicos han estudiado mucho la relaci\u00f3n que hay entre la for<\/span><span style=\"text-align: justify;line-height: 1.5em\">ma de una mol\u00e9cul<\/span><span style=\"text-align: justify;line-height: 1.5em\">a y su color.\u00a0<\/span><span style=\"line-height: 1.5em\">Actual<\/span><span style=\"line-height: 1.5em\">mente y con la ayuda de las computadoras es posible saber de qu\u00e9\u00a0<\/span><span style=\"line-height: 1.5em\">color es un compuesto antes de elaborarlo en el laboratorio. Los qu\u00edmico<\/span><span style=\"line-height: 1.5em\">s investigan nuevas sustancias\u00a0<\/span><span style=\"line-height: 1.5em\">para hacer m\u00e1s colorido nuestro mundo. Todav\u00eda se buscan nuevos compuestos para colorear nuestros alimentos, algunos que pueda<\/span><span style=\"line-height: 1.5em\">n unirse a la ropa con m\u00e1<\/span><span style=\"line-height: 1.5em\">s fuerza para que no se decolore, que sean m\u00e1s baratos y que tengan mayores aplicaciones. Hace cien a\u00f1os nuestra sociedad no era tan colorida como ahora y si a<\/span><span style=\"line-height: 1.5em\">lg\u00fan joven lector se interesa en el estudio de esta disciplina nuestro futuro ser\u00e1 aun m\u00e1s colorido.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.uv.mx\/cienciauv\/files\/2014\/06\/CienciaLuz26.pdf\">Descargar versi\u00f3n impresa<\/a><\/p>\n<p><span style=\"line-height: 1.5em\">*Facultad de Ciencias Qu\u00edmicas-Orizaba, Universidad Veracruzana<\/span><\/p>\n<p>Dudas y comentarios: dcc@uv.mx<\/p>\n<p>Ilustraci\u00f3n: Sergio A. Segura Medrano.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0Ra\u00fal Colorado Peralta y Jos\u00e9 Mar\u00eda Rivera* Nuestro mundo se ve muy bien a colores, a todos nos gusta contemplar el campo verde, el cielo azul o las flores. Pero no s\u00f3lo la naturaleza es colorida, nos gustan tanto los colores que los capturamos en nuestros objetos, pintamos nuestras casas, te\u00f1imos la ropa, imprimimos [&hellip;]<\/p>\n","protected":false},"author":1746,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ventana_nueva":"","tipo_url":"","url":"","extracto":"","imagen_halign":"","imagen_valign":"","bg_size":"","text_hide":"","media_url":"","tipo_media":"","video_url":"","video_pos":"","video_youtube":"","footnotes":""},"categories":[28],"tags":[],"class_list":["post-2840","post","type-post","status-publish","format-standard","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/www.uv.mx\/cienciauv\/wp-json\/wp\/v2\/posts\/2840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uv.mx\/cienciauv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uv.mx\/cienciauv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uv.mx\/cienciauv\/wp-json\/wp\/v2\/users\/1746"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uv.mx\/cienciauv\/wp-json\/wp\/v2\/comments?post=2840"}],"version-history":[{"count":0,"href":"https:\/\/www.uv.mx\/cienciauv\/wp-json\/wp\/v2\/posts\/2840\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.uv.mx\/cienciauv\/wp-json\/wp\/v2\/media?parent=2840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uv.mx\/cienciauv\/wp-json\/wp\/v2\/categories?post=2840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uv.mx\/cienciauv\/wp-json\/wp\/v2\/tags?post=2840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}